{"id":7729,"date":"2017-01-09T09:22:28","date_gmt":"2017-01-09T08:22:28","guid":{"rendered":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg"},"modified":"2017-01-09T09:23:32","modified_gmt":"2017-01-09T08:23:32","slug":"p1080365_aarescalers","status":"inherit","type":"attachment","link":"https:\/\/www.funktionsmodellbau.ch\/content\/aare-scalers-rc-tour-entlang-der-aare-bei-aarau\/p1080365_aarescalers\/","title":{"rendered":"P1080365_aarescalers"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>P1080365_aarescalers - funktionsmodellbau.ch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P1080365_aarescalers - funktionsmodellbau.ch\" \/>\n<meta property=\"og:description\" content=\"by Aare Scalers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg\" \/>\n<meta property=\"og:site_name\" content=\"funktionsmodellbau.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/funktionsmodellbau\/\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-09T08:23:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?fit=2048%2C1536&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@funktionsmodell\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg\",\"url\":\"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg\",\"name\":\"P1080365_aarescalers - funktionsmodellbau.ch\",\"isPartOf\":{\"@id\":\"https:\/\/www.funktionsmodellbau.ch\/content\/#website\"},\"datePublished\":\"2017-01-09T08:22:28+00:00\",\"dateModified\":\"2017-01-09T08:23:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.funktionsmodellbau.ch\/content\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aare Scalers &#8211; RC Tour entlang der Aare bei Aarau\",\"item\":\"https:\/\/www.funktionsmodellbau.ch\/content\/aare-scalers-rc-tour-entlang-der-aare-bei-aarau\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"P1080365_aarescalers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.funktionsmodellbau.ch\/content\/#website\",\"url\":\"https:\/\/www.funktionsmodellbau.ch\/content\/\",\"name\":\"funktionsmodellbau.ch\",\"description\":\"RC MODELLNUTZFAHRZEUGE | RC TRUCK-MODELLBAU | RC SCALE CARS | RC BOOTE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.funktionsmodellbau.ch\/content\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P1080365_aarescalers - funktionsmodellbau.ch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg","og_locale":"de_DE","og_type":"article","og_title":"P1080365_aarescalers - funktionsmodellbau.ch","og_description":"by Aare Scalers","og_url":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg","og_site_name":"funktionsmodellbau.ch","article_publisher":"https:\/\/www.facebook.com\/funktionsmodellbau\/","article_modified_time":"2017-01-09T08:23:32+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/i1.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?fit=2048%2C1536&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@funktionsmodell","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg","url":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg","name":"P1080365_aarescalers - funktionsmodellbau.ch","isPartOf":{"@id":"https:\/\/www.funktionsmodellbau.ch\/content\/#website"},"datePublished":"2017-01-09T08:22:28+00:00","dateModified":"2017-01-09T08:23:32+00:00","breadcrumb":{"@id":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.funktionsmodellbau.ch\/content\/"},{"@type":"ListItem","position":2,"name":"Aare Scalers &#8211; RC Tour entlang der Aare bei Aarau","item":"https:\/\/www.funktionsmodellbau.ch\/content\/aare-scalers-rc-tour-entlang-der-aare-bei-aarau\/"},{"@type":"ListItem","position":3,"name":"P1080365_aarescalers"}]},{"@type":"WebSite","@id":"https:\/\/www.funktionsmodellbau.ch\/content\/#website","url":"https:\/\/www.funktionsmodellbau.ch\/content\/","name":"funktionsmodellbau.ch","description":"RC MODELLNUTZFAHRZEUGE | RC TRUCK-MODELLBAU | RC SCALE CARS | RC BOOTE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.funktionsmodellbau.ch\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"by Aare Scalers\" srcset=\"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?w=1356&amp;ssl=1 1356w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"7729\" data-permalink=\"https:\/\/www.funktionsmodellbau.ch\/content\/aare-scalers-rc-tour-entlang-der-aare-bei-aarau\/p1080365_aarescalers\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?fit=2048%2C1536&amp;ssl=1\" data-orig-size=\"2048,1536\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"P1080365_aarescalers\" data-image-description=\"&lt;p&gt;by Aare Scalers&lt;\/p&gt;\n\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?fit=678%2C509&amp;ssl=1\" \/><\/a><\/p>\n<p>by Aare Scalers<\/p>\n"},"caption":{"rendered":"<p>by Aare Scalers<\/p>\n"},"alt_text":"by Aare Scalers","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":1536,"file":"2017\/01\/P1080365_aarescalers.jpg","sizes":{"thumbnail":{"file":"P1080365_aarescalers-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"P1080365_aarescalers-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?fit=300%2C225&ssl=1"},"medium_large":{"file":"P1080365_aarescalers-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?fit=678%2C509&ssl=1"},"large":{"file":"P1080365_aarescalers-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?fit=678%2C509&ssl=1"},"shareaholic-thumbnail":{"file":"P1080365_aarescalers-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?fit=300%2C225&ssl=1"},"featured-slider":{"file":"P1080365_aarescalers-754x400.jpg","width":754,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?resize=754%2C400&ssl=1"},"featured-slider-larger":{"file":"P1080365_aarescalers-1190x500.jpg","width":1190,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?resize=1190%2C500&ssl=1"},"jetpack-portfolio-admin-thumb":{"file":"P1080365_aarescalers-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?resize=50%2C50&ssl=1"},"full":{"file":"P1080365_aarescalers.jpg?fit=2048%2C1536&ssl=1","width":2048,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg?fit=2048%2C1536&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"optimus":{"profit":"7","quantity":63,"webp":0}},"post":7714,"source_url":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-content\/uploads\/2017\/01\/P1080365_aarescalers.jpg","_links":{"self":[{"href":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-json\/wp\/v2\/media\/7729"}],"collection":[{"href":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.funktionsmodellbau.ch\/content\/wp-json\/wp\/v2\/comments?post=7729"}]}}